{"id":1002,"count":1,"description":"","link":"https:\/\/saltavecinal.com\/index.php\/tag\/balnearios\/","name":"balnearios","slug":"balnearios","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/saltavecinal.com\/index.php\/wp-json\/wp\/v2\/tags\/1002"}],"collection":[{"href":"https:\/\/saltavecinal.com\/index.php\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/saltavecinal.com\/index.php\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/saltavecinal.com\/index.php\/wp-json\/wp\/v2\/posts?tags=1002"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}